{"id":1777,"date":"2025-09-05T08:00:57","date_gmt":"2025-09-05T06:00:57","guid":{"rendered":"https:\/\/nwcluster.no\/?p=1777"},"modified":"2025-09-05T08:42:27","modified_gmt":"2025-09-05T06:42:27","slug":"erstes-wiederverwendungszentrum-fur-baumaterialien-in-binnennorwegen-49","status":"publish","type":"post","link":"https:\/\/nwcluster.no\/de\/erstes-wiederverwendungszentrum-fur-baumaterialien-in-binnennorwegen-49\/","title":{"rendered":"N\u00fctzliche Wiederverwendungsdaten von Ragn-Sells"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row row_height_percent=&#8220;0&#8243; overlay_alpha=&#8220;50&#8243; gutter_size=&#8220;3&#8243; column_width_use_pixel=&#8220;yes&#8220; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; content_parallax=&#8220;0&#8243; uncode_shortcode_id=&#8220;166316&#8243; column_width_pixel=&#8220;900&#8243;][vc_column width=&#8220;1\/1&#8243;][vc_column_text text_color=&#8220;color-prif&#8220; uncode_shortcode_id=&#8220;294478&#8243; text_color_type=&#8220;uncode-palette&#8220;]Die vom Interreg-Projekt Circular Bioeconomy Arena am 1. und 2. September in G\u00f6teborg organisierte Wiederverwendungskonferenz stand unter dem Motto &#8222;Neue Rollen und Logistik&#8220;. Die Teilnehmer hatten das Vergn\u00fcgen, Jon Lille-Schulstad, Director of Business Development bei Ragn-Sells AS, \u00fcber die Ergebnisse der in Norwegen durchgef\u00fchrten Tests sprechen zu h\u00f6ren. <\/p>\n<h4><strong>Betonpr\u00fcfung und -analyse<\/strong><\/h4>\n<p>Wie der norwegische Holzcluster war auch Ragn-Sells ein Partner in dem umfangreichen Projekt der Gr\u00fcnen Plattform SirkTRE, das jetzt abgeschlossen wurde. Ziel von SirkTRE war es, eine zirkul\u00e4re Wertsch\u00f6pfungskette f\u00fcr recyceltes Holz zu kartieren und zu etablieren, indem die Wiederverwendung und Materialr\u00fcckgewinnung von recyceltem Holz in der Praxis erleichtert und demonstriert wird. <\/p>\n<p>&#8211; Normalerweise werden gebrauchte Materialien so verarbeitet, dass sie nicht f\u00fcr die Wiederverwendung zur\u00fcckgewonnen werden k\u00f6nnen. Wir haben uns an SirkTRE und dem parallel laufenden Forschungsprojekt CircWOOD beteiligt, um Erkenntnisse und Erfahrungen beizusteuern, in der Hoffnung, konkrete L\u00f6sungen zu finden, die sich in gr\u00f6\u00dferem Ma\u00dfstab umsetzen lassen. Im Rahmen von CircWOOD haben wir Analysen erleichtert, Daten \u00fcber Mengen und Qualit\u00e4ten von Holzabf\u00e4llen sowie Informationen \u00fcber Handhabung und Sortierung bereitgestellt&#8220;, sagte Jon Lille-Schulstad vor einem aufmerksamen Publikum in G\u00f6teborg.  <\/p>\n<h4><strong>Datenerfassung in Moss und Hamar<\/strong><\/h4>\n<p>NIBIO hat in den Anlagen von Ragn-Sell in Moss und Hamar Kommissionieranalysen durchgef\u00fchrt. Insgesamt wurden 46,4 Tonnen Abfall untersucht. Die Sortieranalyse zeigte, dass die Holzabf\u00e4lle aus der Bauindustrie einen h\u00f6heren Anteil an unlackiertem Holz oder Holzabf\u00e4llen aufwiesen als die aus Haushalten\/Recyclingzentren. Die Holzabf\u00e4lle, die aus der Industrie und dem Dienstleistungsgewerbe kamen, bestanden haupts\u00e4chlich aus Holzverpackungen in Form von Paletten.   <\/p>\n<p>&#8211; &#8222;W\u00e4hrend Einwegpaletten und Verpackungen im Grunde genommen hervorragende Rohstoffe f\u00fcr die Kartonherstellung sind, ist das Sammeln und Verarbeiten von gebrauchtem Holzmaterial anspruchsvoller&#8220;, sagt Jon Lille-Schulstad.<\/p>\n<h4><strong>Erfahrungen von der Baustelle<\/strong><\/h4>\n<p>&#8211; &#8222;Wir haben gelernt, dass die Sammlung von Wertstoffen nicht zuletzt von einem engagierten Baumanagement und einer guten Information und Schulung der Mitarbeiter abh\u00e4ngt. Dar\u00fcber hinaus muss die Sortierl\u00f6sung auf der Baustelle leicht zug\u00e4nglich sein&#8220;, so Jon Lille-Schulstad. <\/p>\n<p>&#8211; Ragn-Sells testete mehrere L\u00f6sungen f\u00fcr das Sammeln von Materialien auf Baustellen. &#8222;Unsere Erfahrung war, dass wir mit der richtigen L\u00f6sung die F\u00fcllrate erh\u00f6hten, nur wenige Abweichungen hatten und es schafften, Holzmaterialien zu sammeln, deren Qualit\u00e4t gut genug war, um sie direkt der Wiederverwendung zuzuf\u00fchren&#8220;, sagte Jon Lille-Schulstad. Er erkl\u00e4rte, dass die visuelle Qualit\u00e4tsbewertung des gesammelten Recyclingholzes durch NIBIO und Treteknisk ergab, dass mehr als 50 Prozent eine gute oder ausgezeichnete Qualit\u00e4t aufwiesen.  <\/p>\n<h4><strong>Zusammenarbeit zwischen Ragn-Sells und Norsk Massivtre<\/strong><\/h4>\n<p>&#8211; &#8222;Im Rahmen des SirkTRE-Projekts haben wir die Verwendung von gesammeltem Recyclingholz bei Norsk Massivtre getestet. Unsere Erfahrungen waren so interessant, dass wir diese Zusammenarbeit nun nach dem Ende des SirkTRE-Projekts weiter ausbauen&#8220;, sagt Jon Lille-Schulstad, Direktor f\u00fcr Gesch\u00e4ftsentwicklung bei Ragn-Sells AS.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row row_height_percent=&#8220;0&#8243; overlay_alpha=&#8220;50&#8243; gutter_size=&#8220;3&#8243; column_width_use_pixel=&#8220;yes&#8220; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; content_parallax=&#8220;0&#8243; uncode_shortcode_id=&#8220;166316&#8243; column_width_pixel=&#8220;900&#8243;][vc_column width=&#8220;1\/2&#8243;][vc_single_image media=&#8220;1834&#8243; caption=&#8220;yes&#8220; media_width_percent=&#8220;100&#8243; media_ratio=&#8220;four-three&#8220; uncode_shortcode_id=&#8220;190982&#8243;][\/vc_column][vc_column width=&#8220;1\/2&#8243;][vc_single_image media=&#8220;1837&#8243; caption=&#8220;yes&#8220; media_width_percent=&#8220;100&#8243; media_ratio=&#8220;four-three&#8220; uncode_shortcode_id=&#8220;809889&#8243;][\/vc_column][\/vc_row][vc_row row_height_percent=&#8220;0&#8243; overlay_alpha=&#8220;50&#8243; gutter_size=&#8220;3&#8243; column_width_use_pixel=&#8220;yes&#8220; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; content_parallax=&#8220;0&#8243; uncode_shortcode_id=&#8220;166316&#8243; column_width_pixel=&#8220;900&#8243;][vc_column width=&#8220;1\/1&#8243;][vc_single_image media=&#8220;1840&#8243; caption=&#8220;yes&#8220; media_width_percent=&#8220;100&#8243; uncode_shortcode_id=&#8220;809089&#8243;][\/vc_column][\/vc_row][vc_row row_height_percent=&#8220;0&#8243; back_color=&#8220;color-190797&#8243; overlay_alpha=&#8220;50&#8243; gutter_size=&#8220;3&#8243; column_width_use_pixel=&#8220;yes&#8220; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; content_parallax=&#8220;0&#8243; uncode_shortcode_id=&#8220;181566&#8243; column_width_pixel=&#8220;900&#8243; back_color_type=&#8220;uncode-palette&#8220;][vc_column width=&#8220;1\/1&#8243;][vc_column_text uncode_shortcode_id=&#8220;197893&#8243;]<\/p>\n<h4><strong>Arena der zirkul\u00e4ren Bio\u00f6konomie<\/strong><\/h4>\n<p>Norwegian Wood Cluster ist der norwegische Eigent\u00fcmer des Interreg-Projekts Circular Bioeconomy Arena. Der schwedische Eigent\u00fcmer ist Paper Province, und der Projektleiter ist Gry Lenschow Andersen von Paper Province. In dem Projekt arbeiten wir eng mit Innovatum Science Park, Dalerna Science Park, Byggdialog Dalerna, Sting Innovation, Klosser Innovation, Kjeller Innovation und Circular Packaging Cluster zusammen. Die zirkul\u00e4re Holzkonstruktion hat einen starken Fokus in dem Projekt. Es arbeitet auch mit Start-up-Unternehmen auf norwegischer und schwedischer Seite zusammen, die in der forstwirtschaftlichen Bio\u00f6konomie t\u00e4tig sind.    <\/p>\n<p>Das Projekt wird von Interreg Schweden-Norwegen und EU-Mitteln sowie mit Unterst\u00fctzung von Innlandet County Council, Akershus County Council, Buskerud County Council, \u00d8stfold County Council, Region V\u00e4rmland, Region V\u00e4stra G\u00f6taland, Region Dalerna, Vinnova und DNB finanziert.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>In Norwegen wurden Kommissionieranalysen durchgef\u00fchrt, um Daten und Erfahrungen im Zusammenhang mit dem Recycling von Holzmaterialien zu sammeln. Dies geschah im Rahmen des umfangreichen Projekts SirkTRE\/CircWOOD und wurde von Ragn-Sells in enger Zusammenarbeit mit NIBIO und Treteknisk durchgef\u00fchrt. <\/p>\n","protected":false},"author":4,"featured_media":1833,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[23],"tags":[],"class_list":["post-1777","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-was-ist-neu"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>N\u00fctzliche Wiederverwendungsdaten von Ragn-Sells - Norwegian Wood Cluster<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nwcluster.no\/de\/erstes-wiederverwendungszentrum-fur-baumaterialien-in-binnennorwegen-49\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"N\u00fctzliche Wiederverwendungsdaten von Ragn-Sells - Norwegian Wood Cluster\" \/>\n<meta property=\"og:description\" content=\"In Norwegen wurden Kommissionieranalysen durchgef\u00fchrt, um Daten und Erfahrungen im Zusammenhang mit dem Recycling von Holzmaterialien zu sammeln. Dies geschah im Rahmen des umfangreichen Projekts SirkTRE\/CircWOOD und wurde von Ragn-Sells in enger Zusammenarbeit mit NIBIO und Treteknisk durchgef\u00fchrt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nwcluster.no\/de\/erstes-wiederverwendungszentrum-fur-baumaterialien-in-binnennorwegen-49\/\" \/>\n<meta property=\"og:site_name\" content=\"Norwegian Wood Cluster\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-05T06:00:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-05T06:42:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nwcluster.no\/wp-content\/uploads\/2025\/09\/Jon-Lille-Schulstad-foto-MBN-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mari Blokhus Nordtun\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mari Blokhus Nordtun\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nwcluster.no\/de\/erstes-wiederverwendungszentrum-fur-baumaterialien-in-binnennorwegen-49\/\",\"url\":\"https:\/\/nwcluster.no\/de\/erstes-wiederverwendungszentrum-fur-baumaterialien-in-binnennorwegen-49\/\",\"name\":\"N\u00fctzliche Wiederverwendungsdaten von Ragn-Sells - Norwegian Wood Cluster\",\"isPartOf\":{\"@id\":\"https:\/\/nwcluster.no\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nwcluster.no\/de\/erstes-wiederverwendungszentrum-fur-baumaterialien-in-binnennorwegen-49\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nwcluster.no\/de\/erstes-wiederverwendungszentrum-fur-baumaterialien-in-binnennorwegen-49\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nwcluster.no\/wp-content\/uploads\/2025\/09\/Jon-Lille-Schulstad-foto-MBN-scaled.jpg\",\"datePublished\":\"2025-09-05T06:00:57+00:00\",\"dateModified\":\"2025-09-05T06:42:27+00:00\",\"author\":{\"@id\":\"https:\/\/nwcluster.no\/de\/#\/schema\/person\/5cface82763c66df62d78fc06578870e\"},\"breadcrumb\":{\"@id\":\"https:\/\/nwcluster.no\/de\/erstes-wiederverwendungszentrum-fur-baumaterialien-in-binnennorwegen-49\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nwcluster.no\/de\/erstes-wiederverwendungszentrum-fur-baumaterialien-in-binnennorwegen-49\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/nwcluster.no\/de\/erstes-wiederverwendungszentrum-fur-baumaterialien-in-binnennorwegen-49\/#primaryimage\",\"url\":\"https:\/\/nwcluster.no\/wp-content\/uploads\/2025\/09\/Jon-Lille-Schulstad-foto-MBN-scaled.jpg\",\"contentUrl\":\"https:\/\/nwcluster.no\/wp-content\/uploads\/2025\/09\/Jon-Lille-Schulstad-foto-MBN-scaled.jpg\",\"width\":2560,\"height\":1920,\"caption\":\"Spennende \u00e5 h\u00f8re Jon Lille-Schulstad, direkt\u00f8r for forretningsutvikling i Ragn-Sells AS, fortelle om resultatene fra deres testing av innsamling av returtre under ombrukskonferansen til interregprosjektet Circular Bioeconomy Arena. FOTO: Berit Sanness\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nwcluster.no\/de\/erstes-wiederverwendungszentrum-fur-baumaterialien-in-binnennorwegen-49\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nwcluster.no\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"N\u00fctzliche Wiederverwendungsdaten von Ragn-Sells\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nwcluster.no\/de\/#website\",\"url\":\"https:\/\/nwcluster.no\/de\/\",\"name\":\"Norwegian Wood Cluster\",\"description\":\"Vi gir verden innovative ogb\u00e6rekraftige byggel\u00f8sninger i tre\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nwcluster.no\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/nwcluster.no\/de\/#\/schema\/person\/5cface82763c66df62d78fc06578870e\",\"name\":\"Mari Blokhus Nordtun\",\"url\":\"https:\/\/nwcluster.no\/de\/author\/adminmari\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"N\u00fctzliche Wiederverwendungsdaten von Ragn-Sells - Norwegian Wood Cluster","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nwcluster.no\/de\/erstes-wiederverwendungszentrum-fur-baumaterialien-in-binnennorwegen-49\/","og_locale":"de_DE","og_type":"article","og_title":"N\u00fctzliche Wiederverwendungsdaten von Ragn-Sells - Norwegian Wood Cluster","og_description":"In Norwegen wurden Kommissionieranalysen durchgef\u00fchrt, um Daten und Erfahrungen im Zusammenhang mit dem Recycling von Holzmaterialien zu sammeln. Dies geschah im Rahmen des umfangreichen Projekts SirkTRE\/CircWOOD und wurde von Ragn-Sells in enger Zusammenarbeit mit NIBIO und Treteknisk durchgef\u00fchrt.","og_url":"https:\/\/nwcluster.no\/de\/erstes-wiederverwendungszentrum-fur-baumaterialien-in-binnennorwegen-49\/","og_site_name":"Norwegian Wood Cluster","article_published_time":"2025-09-05T06:00:57+00:00","article_modified_time":"2025-09-05T06:42:27+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/nwcluster.no\/wp-content\/uploads\/2025\/09\/Jon-Lille-Schulstad-foto-MBN-scaled.jpg","type":"image\/jpeg"}],"author":"Mari Blokhus Nordtun","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Mari Blokhus Nordtun","Est. reading time":"4 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nwcluster.no\/de\/erstes-wiederverwendungszentrum-fur-baumaterialien-in-binnennorwegen-49\/","url":"https:\/\/nwcluster.no\/de\/erstes-wiederverwendungszentrum-fur-baumaterialien-in-binnennorwegen-49\/","name":"N\u00fctzliche Wiederverwendungsdaten von Ragn-Sells - Norwegian Wood Cluster","isPartOf":{"@id":"https:\/\/nwcluster.no\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nwcluster.no\/de\/erstes-wiederverwendungszentrum-fur-baumaterialien-in-binnennorwegen-49\/#primaryimage"},"image":{"@id":"https:\/\/nwcluster.no\/de\/erstes-wiederverwendungszentrum-fur-baumaterialien-in-binnennorwegen-49\/#primaryimage"},"thumbnailUrl":"https:\/\/nwcluster.no\/wp-content\/uploads\/2025\/09\/Jon-Lille-Schulstad-foto-MBN-scaled.jpg","datePublished":"2025-09-05T06:00:57+00:00","dateModified":"2025-09-05T06:42:27+00:00","author":{"@id":"https:\/\/nwcluster.no\/de\/#\/schema\/person\/5cface82763c66df62d78fc06578870e"},"breadcrumb":{"@id":"https:\/\/nwcluster.no\/de\/erstes-wiederverwendungszentrum-fur-baumaterialien-in-binnennorwegen-49\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nwcluster.no\/de\/erstes-wiederverwendungszentrum-fur-baumaterialien-in-binnennorwegen-49\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/nwcluster.no\/de\/erstes-wiederverwendungszentrum-fur-baumaterialien-in-binnennorwegen-49\/#primaryimage","url":"https:\/\/nwcluster.no\/wp-content\/uploads\/2025\/09\/Jon-Lille-Schulstad-foto-MBN-scaled.jpg","contentUrl":"https:\/\/nwcluster.no\/wp-content\/uploads\/2025\/09\/Jon-Lille-Schulstad-foto-MBN-scaled.jpg","width":2560,"height":1920,"caption":"Spennende \u00e5 h\u00f8re Jon Lille-Schulstad, direkt\u00f8r for forretningsutvikling i Ragn-Sells AS, fortelle om resultatene fra deres testing av innsamling av returtre under ombrukskonferansen til interregprosjektet Circular Bioeconomy Arena. FOTO: Berit Sanness"},{"@type":"BreadcrumbList","@id":"https:\/\/nwcluster.no\/de\/erstes-wiederverwendungszentrum-fur-baumaterialien-in-binnennorwegen-49\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nwcluster.no\/de\/"},{"@type":"ListItem","position":2,"name":"N\u00fctzliche Wiederverwendungsdaten von Ragn-Sells"}]},{"@type":"WebSite","@id":"https:\/\/nwcluster.no\/de\/#website","url":"https:\/\/nwcluster.no\/de\/","name":"Norwegian Wood Cluster","description":"Vi gir verden innovative ogb\u00e6rekraftige byggel\u00f8sninger i tre","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nwcluster.no\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/nwcluster.no\/de\/#\/schema\/person\/5cface82763c66df62d78fc06578870e","name":"Mari Blokhus Nordtun","url":"https:\/\/nwcluster.no\/de\/author\/adminmari\/"}]}},"_links":{"self":[{"href":"https:\/\/nwcluster.no\/de\/wp-json\/wp\/v2\/posts\/1777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nwcluster.no\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nwcluster.no\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nwcluster.no\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/nwcluster.no\/de\/wp-json\/wp\/v2\/comments?post=1777"}],"version-history":[{"count":0,"href":"https:\/\/nwcluster.no\/de\/wp-json\/wp\/v2\/posts\/1777\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nwcluster.no\/de\/wp-json\/wp\/v2\/media\/1833"}],"wp:attachment":[{"href":"https:\/\/nwcluster.no\/de\/wp-json\/wp\/v2\/media?parent=1777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nwcluster.no\/de\/wp-json\/wp\/v2\/categories?post=1777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nwcluster.no\/de\/wp-json\/wp\/v2\/tags?post=1777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}